{"id":14075,"date":"2022-04-08T11:07:42","date_gmt":"2022-04-08T03:07:42","guid":{"rendered":"http:\/\/hzcork.com\/?post_type=product&#038;p=14075"},"modified":"2022-04-08T15:18:09","modified_gmt":"2022-04-08T07:18:09","slug":"black-trifold-cork-wallet","status":"publish","type":"product","link":"https:\/\/hzcork.com\/fr\/black-trifold-cork-wallet\/","title":{"rendered":"Portefeuille trifold en li\u00e8ge noir"},"content":{"rendered":"<p>Q1, Les sacs \u00e0 main en li\u00e8ge sont-ils durables ?<\/p>\n<p>La structure alv\u00e9olaire du li\u00e8ge en fait un excellent isolant thermique et acoustique. Le coefficient de frottement \u00e9lev\u00e9 du li\u00e8ge signifie \u00e9galement que <b>il est durable dans les situations o\u00f9 il y a r\u00e9guli\u00e8rement des frottements et de l'abrasion<\/b>. C'est pourquoi le li\u00e8ge est un mat\u00e9riau de choix, m\u00eame pour la NASA.<\/p>\n<p>Q2, Quelle est la dur\u00e9e de vie des sacs \u00e0 main en li\u00e8ge ?<\/p>\n<p>Comme vous le savez, la partie la plus importante des sacs en li\u00e8ge comprend le tissu en li\u00e8ge, la doublure et la quincaillerie. Le tissu en li\u00e8ge est durable, le mat\u00e9riel que nous utilisons est tr\u00e8s robuste, ils vous dureront donc longtemps. <b>une vie<\/b>M\u00eame si vous les portez tous les jours. Nous utilisons \u00e9galement un rembourrage doux \u00e0 l'int\u00e9rieur pour conserver une forme parfaite.<\/p>\n<p>Q3, Comment entretenir les sacs \u00e0 main en li\u00e8ge ?<\/p>\n<p>Il est facile de garder les sacs de li\u00e8ge propres, il suffit de <b>tremper une petite serviette dans de l'eau chaude<\/b> (m\u00e9lang\u00e9 \u00e0 un peu de savon doux) et frotter les taches ou les marques noires sur la surface du li\u00e8ge.<\/p>\n<p>Q4, peut-on laver les sacs \u00e0 main en li\u00e8ge, sont-ils imperm\u00e9ables ?<\/p>\n<p>Oui, le li\u00e8ge est imperm\u00e9able, vous pouvez le mouiller sans crainte. Pensez au bouchon de vin. Mais nous ne conseillons pas de plonger les sacs de li\u00e8ge dans l'eau pendant longtemps, ni dans la machine \u00e0 laver.<\/p>\n<p>Comme le tissu de li\u00e8ge adh\u00e8re \u00e0 un support textile, la colle est \u00e0 base d'eau.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ce portefeuille en li\u00e8ge noir est deux fois plus l\u00e9ger qu'un portefeuille en cuir et, comme le li\u00e8ge est extensible, il ne craint pas d'\u00eatre d\u00e9form\u00e9 par un jean. Il est facile \u00e0 transporter au quotidien et poss\u00e8de de nombreuses poches int\u00e9rieures pour accueillir plusieurs cartes de cr\u00e9dit.<\/p>\n<p>- 100% Sans animaux, mat\u00e9riau durable<\/p>\n<p>- Li\u00e8ge naturel, certifi\u00e9 FSC<\/p>\n<p>- Produit fabriqu\u00e9 en Chine avec du li\u00e8ge portugais<\/p>\n<p>- Respectueux de l'environnement, durable, recyclable et doux au toucher<\/p>\n<p><strong>Diff\u00e9rents motifs et couleurs pour un large choix. Les OEM et les conceptions personnalis\u00e9es sont les bienvenus.<\/strong><\/p>\n<p><strong>Les petites quantit\u00e9s, les livraisons rapides et les constructions complexes sont possibles. Sans probl\u00e8me de d\u00e9coloration.<\/strong><\/p>\n<p>Caract\u00e9ristiques :<\/p>\n<p>Portefeuille trifold avec 6 fentes pour cartes, 1 pochette pour argent liquide, 1 pochette pour pi\u00e8ces de monnaie<br \/>\nPoche centrale zipp\u00e9e pour les affaires personnelles<br \/>\nLe mat\u00e9riau utilis\u00e9 est souple, flexible, durable, fin et l\u00e9ger, ce qui signifie que ce portefeuille cool n'alourdira pas votre poche.<br \/>\nLe profil fin de ce portefeuille se glisse parfaitement dans votre poche avant ou arri\u00e8re, r\u00e9duisant ainsi le stress dorsal.<\/p>","protected":false},"featured_media":14080,"template":"","meta":[],"product_brand":[],"product_cat":[150],"product_tag":[258],"class_list":{"0":"post-14075","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cork-wallets","7":"product_tag-cork-wallet","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/product\/14075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/product\/14075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/media\/14080"}],"wp:attachment":[{"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/media?parent=14075"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/product_brand?post=14075"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/product_cat?post=14075"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hzcork.com\/fr\/wp-json\/wp\/v2\/product_tag?post=14075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}